{"id":7659,"date":"2022-10-05T15:22:08","date_gmt":"2022-10-05T15:22:08","guid":{"rendered":"https:\/\/dascostorage.com\/a-propos-de-nous\/"},"modified":"2025-07-09T16:43:43","modified_gmt":"2025-07-09T16:43:43","slug":"a-propos-de-nous","status":"publish","type":"page","link":"https:\/\/dascostorage.com\/fr\/a-propos-de-nous\/","title":{"rendered":"\u00c0 propos de nous"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"7659\" class=\"elementor elementor-7659 elementor-82\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ee48451 elementor-section-height-min-height elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"ee48451\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8209ea1\" data-id=\"8209ea1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dac6c36 elementor-headline--style-rotate elementor-widget elementor-widget-animated-headline\" data-id=\"dac6c36\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;animation_type&quot;:&quot;slide&quot;,&quot;rotating_text&quot;:&quot;A propos de nous&quot;,&quot;headline_style&quot;:&quot;rotate&quot;,&quot;loop&quot;:&quot;yes&quot;,&quot;rotate_iteration_delay&quot;:2500}\" data-widget_type=\"animated-headline.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h1 class=\"elementor-headline elementor-headline-animation-type-slide\">\n\t\t\t\t<span class=\"elementor-headline-dynamic-wrapper elementor-headline-text-wrapper\">\n\t\t\t\t\t<span class=\"elementor-headline-dynamic-text elementor-headline-text-active\">\n\t\t\t\tA&nbsp;propos&nbsp;de&nbsp;nous\t\t\t<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t<\/h1>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8adf09e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8adf09e\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-aaeb78f\" data-id=\"aaeb78f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b6940ee elementor-widget elementor-widget-heading\" data-id=\"b6940ee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Notre histoire<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7f360ae\" data-id=\"7f360ae\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-08dd29a elementor-widget elementor-widget-text-editor\" data-id=\"08dd29a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Chez DASCO Storage Solutions, nous sommes fiers de fournir les meilleurs produits, ainsi qu\u2019un service \u00e0 la client\u00e8le hors pair.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Nous sommes les\u00a0 leaders de l\u2019industrie, sp\u00e9cialis\u00e9s dans les solutions de stockage s\u00e9curis\u00e9es pour les armes, les pi\u00e8ces \u00e0 conviction, les appareils \u00e9lectroniques et les dossiers confidentiels pour les forces arm\u00e9es, les forces de l\u2019ordre, les minist\u00e8res gouvernementaux et les entreprises priv\u00e9es dans le monde entier.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Fond\u00e9e en 1963, notre entreprise a son si\u00e8ge social en Ontario, au Canada. C\u2019est\u00a0 dans notre \u00e9tablissement que nous concevons, d\u00e9veloppons et fabriquons chaque composane de nos solutions. Nos ing\u00e9nieurs chevronn\u00e9s mettent l\u2019accent sur la\u00a0 conception de produits hautement personnalisables, adapt\u00e9s \u00e0 une grande vari\u00e9t\u00e9 d\u2019applications. <\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fbbb71c elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fbbb71c\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c163736\" data-id=\"c163736\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-400038f elementor-widget elementor-widget-heading\" data-id=\"400038f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Construire pour demain<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-155dfa7 elementor-widget elementor-widget-text-editor\" data-id=\"155dfa7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Nous comprenons ce qu\u2019il faut faire pour innover pour l\u2019avenir. Nous sommes \u00e0 la pointe de l\u2019industrie du stockage s\u00e9curis\u00e9 en mati\u00e8re de cr\u00e9ation de nouveaux produits, de techniques de fabrication et d\u2019avanc\u00e9es technologiques. Nous savons \u00e9galement combien il est important de fabriquer nos produits en pensant \u00e0\u00a0 l\u2019avenir de notre plan\u00e8te. C\u2019est pourquoi, chez DASCO, nous sommes soucieux de\u00a0 l\u2019environnement dans tous nos travaux. <\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cf04cc8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cf04cc8\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-f09920f\" data-id=\"f09920f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4677e9d elementor-widget elementor-widget-heading\" data-id=\"4677e9d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">PRODUITS DE <br>PEINTURE<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e482f51 decorative-icon elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"e482f51\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Layer_1\" viewBox=\"0 0 800 800\"><defs><style>.cls-1{fill:#646b2d;}<\/style><\/defs><path class=\"cls-1\" d=\"M647.54,193.54h-39.63v-49.29c0-8.47-6.9-15.36-15.38-15.36H152.46c-8.47,0-15.36,6.89-15.36,15.36v129.33c0,8.47,6.89,15.36,15.36,15.36h440.07c8.48,0,15.38-6.89,15.38-15.36v-49.29h24.25v88.93H372.49c-8.47,0-15.36,6.89-15.36,15.36v75.32h-19.38c-8.47,0-15.36,6.89-15.36,15.36v236.47c0,8.48,6.89,15.38,15.36,15.38h69.48c8.48,0,15.38-6.9,15.38-15.38v-236.47c0-8.47-6.9-15.36-15.38-15.36h-19.36v-59.94h259.67c8.47,0,15.36-6.9,15.36-15.38v-119.65c0-8.48-6.89-15.38-15.36-15.38Zm-294.41,446.82v-205.73h38.74v205.73h-38.74ZM167.84,258.2v-98.57h409.32v98.57H167.84Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c54ef46 elementor-widget elementor-widget-text-editor\" data-id=\"c54ef46\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><span style=\"font-weight: 400;\">La gamme de peinture en poudre innovante de DASCO n\u2019\u00e9met aucun compos\u00e9\u00a0 chimique ni aucune particule de fum\u00e9e. Nous utilisons \u00e9galement des aspirateurs\u00a0 r\u00e9cup\u00e9r\u00e9s pour collecter l\u2019exc\u00e9dent de peinture afin de le r\u00e9utiliser. Nous veillons\u00a0 \u00e0 ce que notre proc\u00e9d\u00e9 de peinture soit le meilleur pour nos produits, nos utilisateurs et la plan\u00e8te. <\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-327248f\" data-id=\"327248f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-654b97f elementor-widget elementor-widget-heading\" data-id=\"654b97f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Emballage<br>pour l'exp\u00e9dition<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-65c3f20 decorative-icon elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"65c3f20\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Layer_1\" viewBox=\"0 0 800 800\"><defs><style>.cls-1{fill:#646b2d;}<\/style><\/defs><path class=\"cls-1\" d=\"M732.66,341.94l-68.38-109.41-.75-1.34-.5-.33c-.53-.67-1.07-1.26-1.63-1.79-.39-.37-.79-.72-1.24-1.08-.22-.2-.58-.52-1.09-.87-.56-.37-1.06-.62-1.46-.8-.29-.19-.71-.43-1.2-.64l-249.53-108.25c-4.37-1.9-9.38-1.9-13.74,0l-249.56,108.27c-.46,.21-.85,.43-1.13,.61-.35,.16-.86,.4-1.43,.77-.54,.35-.93,.7-1.19,.94-.4,.31-.78,.64-1.13,.98-.67,.63-1.3,1.34-1.88,2.1-.08,.1-.2,.23-.33,.39l-.55,.73-68.59,109.72c-2.62,4.16-3.33,9.27-1.95,14,1.38,4.73,4.73,8.66,9.17,10.75l58.66,27.86v147.75c0,6.58,3.66,12.5,9.55,15.45l249.56,124.46c.75,.37,1.41,.58,1.81,.71l.17,.06c.39,.16,.8,.3,1.2,.42l.15,.04c1.47,.38,2.93,.58,4.35,.58s2.88-.19,4.35-.58l.12-.03c.55-.15,1.01-.34,1.29-.45l.07-.02c.41-.13,1.1-.35,1.87-.73l249.56-124.45c5.89-2.94,9.55-8.86,9.55-15.44v-147.77l58.63-27.85c4.45-2.11,7.79-6.03,9.16-10.71,1.41-4.73,.71-9.84-1.92-14.03Zm-357.2,16l-51.01,89.21-217.58-103.33,50.36-80.55,218.22,94.66Zm-207.72,53l156.36,74.25c2.33,1.11,4.82,1.67,7.4,1.67,6.19,0,11.93-3.33,14.98-8.7l36.27-63.44v224.12l-215.01-107.23v-120.68Zm438.45-169.43l-206.18,89.45-206.16-89.44,206.16-89.44,206.18,89.44Zm-188.92,173.24l36.24,63.41c3.07,5.36,8.81,8.7,14.98,8.7,2.58,0,5.07-.56,7.4-1.67l156.4-74.27v120.7l-215.02,107.23v-224.09Zm275.87-70.94l-217.6,103.33-50.99-89.21,218.25-94.67,50.34,80.54Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-062fd6b elementor-widget elementor-widget-text-editor\" data-id=\"062fd6b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><span style=\"font-weight: 400;\">Nous exp\u00e9dions des milliers de produits chaque ann\u00e9e; vous pouvez donc imaginer la quantit\u00e9 de carton utilis\u00e9e pour l\u2019exp\u00e9dition. C\u2019est pourquoi DASCO ne s\u2019approvisionne que de cartons d\u2019emballage compos\u00e9s \u00e0 95% de mat\u00e9riaux recycl\u00e9s.<\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-2b7a6b7\" data-id=\"2b7a6b7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-867dfa0 elementor-widget elementor-widget-heading\" data-id=\"867dfa0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">RECYCLAGE <br>DU M\u00c9TAL<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-736a5e4 decorative-icon elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"736a5e4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Layer_1\" viewBox=\"0 0 800 800\"><defs><style>.cls-1{fill:#646b2d;}<\/style><\/defs><path class=\"cls-1\" d=\"M404.12,665.43c0,1.02-.82,1.84-1.84,1.84H215.19c-40.6,0-77.79-18.45-102.05-50.63-3.14-4.15-6.14-8.67-8.88-13.39-2.72-4.72-5.15-9.6-7.21-14.53-15.71-37.01-13.1-78.45,7.19-113.61l36.87-63.86c.51-.88,.21-2.01-.67-2.51l-33-19.04c-1.33-.77-1.19-2.73,.23-3.3l141.26-56.63c1.11-.44,2.34,.27,2.51,1.45l21.62,150.65c.22,1.52-1.41,2.62-2.74,1.86l-33-19.06c-.88-.51-2.01-.21-2.51,.67l-36.88,63.87c-2.44,4.22-3.28,8.36-2.56,12.71,.54,3.36,1.84,5.97,2.57,7.23,.71,1.22,2.32,3.65,4.95,5.83,3.43,2.78,7.46,4.13,12.3,4.13h187.09c1.02,0,1.84,.82,1.84,1.84v104.49ZM189.6,395.53l.03,.02c.88,.51,1.18,1.63,.67,2.51l-54.88,95.05c-14.59,25.28-16.49,55.02-5.2,81.61,1.51,3.61,3.25,7.11,5.2,10.49,1.99,3.43,4.16,6.71,6.44,9.72,17.42,23.1,44.13,36.33,73.33,36.33h151.09c1.02,0,1.84-.82,1.84-1.84v-32.49c0-1.02-.82-1.84-1.84-1.84H215.19c-13.12,0-25.25-4.24-35.1-12.26l-.08-.07c-6.63-5.47-10.86-11.5-13.23-15.6-2.42-4.2-5.57-10.94-6.94-19.48-2.05-12.5,.34-25.14,6.94-36.52l54.86-95.02c.51-.88,1.63-1.18,2.51-.67h0c1.33,.77,2.96-.33,2.74-1.86l-4.58-31.95c-.17-1.18-1.4-1.89-2.51-1.45l-29.96,12.01c-1.43,.57-1.57,2.54-.24,3.3Z\"><\/path><path class=\"cls-1\" d=\"M506.26,708.65l-119.69-94.01c-.94-.74-.94-2.16,0-2.89l119.69-94.04c1.21-.95,2.98-.09,2.98,1.45v38.11c0,1.02,.82,1.84,1.84,1.84h73.72c4.87,0,8.91-1.36,12.35-4.17,2.58-2.11,4.21-4.56,4.95-5.83,.68-1.19,1.99-3.83,2.54-7.17,.71-4.33-.13-8.5-2.57-12.74l-93.55-162.02c-.51-.88-.21-2.01,.67-2.51l90.5-52.24c.88-.51,2.01-.21,2.51,.67l93.53,162.03c20.31,35.17,22.93,76.61,7.18,113.69-2,4.78-4.43,9.65-7.18,14.42-2.66,4.62-5.67,9.16-8.92,13.46-24.21,32.14-61.4,50.6-102.02,50.6h-73.72c-1.02,0-1.84,.82-1.84,1.84v38.09c0,1.54-1.77,2.4-2.98,1.45Zm-61.41-94.02l25.41,19.95c1.21,.95,2.98,.09,2.98-1.45v-.03c0-1.02,.82-1.84,1.84-1.84h109.72c29.21,0,55.92-13.23,73.3-36.3,2.38-3.13,4.54-6.39,6.45-9.73,2.01-3.48,3.75-6.98,5.2-10.44,11.32-26.65,9.42-56.4-5.19-81.69h0s-75.53-130.86-75.53-130.86c-.51-.88-1.63-1.18-2.51-.67l-28.14,16.24c-.88,.51-1.18,1.63-.67,2.51l75.55,130.85c6.58,11.41,8.97,24.05,6.91,36.57-1.4,8.48-4.51,15.18-6.88,19.32-2.45,4.22-6.7,10.28-13.36,15.73-9.87,8.04-22,12.28-35.12,12.28h-109.72c-1.02,0-1.84-.82-1.84-1.84v-.04c0-1.54-1.77-2.4-2.98-1.45l-25.41,19.96c-.94,.74-.94,2.16,0,2.89Z\"><\/path><path class=\"cls-1\" d=\"M286.67,371.79l-90.5-52.24c-.88-.51-1.18-1.63-.67-2.51l93.55-162.03c11.36-19.65,27.54-35.92,46.8-47.04,14.74-8.53,30.92-13.92,48.07-16.03,10.34-1.3,21.74-1.31,32.2,0,39.93,4.92,74.51,27.9,94.81,63.06l36.86,63.85c.51,.88,1.63,1.18,2.51,.67l32.98-19.04c1.33-.77,2.96,.33,2.74,1.85l-21.58,150.64c-.17,1.18-1.4,1.89-2.51,1.45l-141.24-56.62c-1.43-.57-1.57-2.53-.24-3.3l32.97-19.04c.88-.51,1.18-1.63,.67-2.51l-36.87-63.86c-2.42-4.21-5.61-7.01-9.73-8.57-3.2-1.21-6.08-1.39-7.52-1.39s-4.32,.18-7.5,1.38c-4.15,1.57-7.33,4.37-9.76,8.57l-93.56,162.04c-.51,.88-1.63,1.18-2.51,.67Zm-41.32-65.42l28.14,16.25c.88,.51,2.01,.21,2.51-.67l75.55-130.86c6.56-11.37,16.31-19.76,28.19-24.25,8.1-3.07,15.48-3.72,20.24-3.72s12.14,.65,20.26,3.72c11.87,4.48,21.61,12.87,28.18,24.25l54.86,95.02c.51,.88,.21,2.01-.67,2.51l-.03,.02c-1.33,.77-1.19,2.73,.24,3.3l29.99,12.02c1.11,.44,2.34-.27,2.51-1.45l4.58-31.97c.22-1.52-1.41-2.62-2.74-1.86h-.02c-.88,.52-2.01,.22-2.51-.66l-54.86-95.03c-14.6-25.28-39.42-41.8-68.09-45.33-7.58-.96-15.83-.95-23.31,0-12.38,1.52-23.97,5.38-34.5,11.47-13.81,7.97-25.44,19.69-33.64,33.88l-75.55,130.85c-.51,.88-.21,2.01,.67,2.51Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ac8997d elementor-widget elementor-widget-text-editor\" data-id=\"ac8997d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><span style=\"font-weight: 400;\">Nous recyclons tous nos r\u00e9sidus de m\u00e9taux. Le d\u00e9coupage, l\u2019emboutissage et la\u00a0 fabrication de l\u2019acier peuvent g\u00e9n\u00e9rer une grande quantit\u00e9 de r\u00e9sidus. Afin d\u2019\u00e9viter tout gaspillage, des convoyeurs sont install\u00e9s sur les machines concern\u00e9es pour acheminer automatiquement les rebuts vers les bacs de r\u00e9cup\u00e9ration.<\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-60ed7ab elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"60ed7ab\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6dea1d0\" data-id=\"6dea1d0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bf9cd8f elementor-widget elementor-widget-menu-anchor\" data-id=\"bf9cd8f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"Declarationsgarantie\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-85246b1 elementor-widget elementor-widget-heading\" data-id=\"85246b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Nos d\u00e9clarations de garantie<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-435e54e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"435e54e\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-edb9dac\" data-id=\"edb9dac\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-858cde6 elementor-widget elementor-widget-heading\" data-id=\"858cde6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">D\u00e9claration de garantie g\u00e9n\u00e9rale de Dasco<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-51fe5e4 elementor-widget elementor-widget-text-editor\" data-id=\"51fe5e4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">DASCO Storage Solutions garantit que ses produits sont exempts de d\u00e9fauts de\u00a0 fabrication et de mat\u00e9riaux pendant 15 ans \u00e0 compter de la date\u00a0 d\u2019acquisition. Notre responsabilit\u00e9 se limite \u00e0 la r\u00e9paration ou au remplacement sans frais. Si le produit est couvert par la garantie, DASCO prendra en charge les frais de transport. Toutefois, nous nous r\u00e9servons le droit d\u2019annuler la garantie si nous estimons que le produit a fait l\u2019objet d\u2019une mauvaise manipulation ou d\u2019un\u00a0 abus ou qu\u2019il a \u00e9t\u00e9 utilis\u00e9 \u00e0 d\u2019autres fins que celles pour lesquelles il a \u00e9t\u00e9 con\u00e7u.<\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1212b23 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1212b23\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-87a5d45\" data-id=\"87a5d45\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c4d3468 elementor-widget elementor-widget-heading\" data-id=\"c4d3468\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">D\u00e9claration de garantie Dasco E-Locker<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-96cc5fa elementor-widget elementor-widget-text-editor\" data-id=\"96cc5fa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">DASCO Storage Solutions garantit que ses E-Lockers sont exempts de d\u00e9fauts de\u00a0 fabrication et de mat\u00e9riaux pendant 3 ans \u00e0 compter de la date d\u2019achat et\u00a0 d\u2019un contrat de licence de 3 ans. DASCO prendra en charge des frais de transport\u00a0 raisonnables des produits ou des pi\u00e8ces \u00e0 destination et en provenance de notre centre de r\u00e9paration d\u00e9sign\u00e9, si le produit ou la pi\u00e8ce est consid\u00e9r\u00e9 comme \u00e9tant\u00a0 sous garantie. Toutefois, nous nous r\u00e9servons le droit d\u2019annuler la garantie si nous\u00a0 estimons que le produit a fait l\u2019objet d\u2019une mauvaise manipulation ou d\u2019un abus ou\u00a0 qu\u2019il a \u00e9t\u00e9 utilis\u00e9 \u00e0 d\u2019autres fins que celles pour lesquelles il a \u00e9t\u00e9 con\u00e7u.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Licences de garantie prolong\u00e9e et contrats de services disponibles.<\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1693d84 elementor-widget elementor-widget-text-editor\" data-id=\"1693d84\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Pour toute question ou pr\u00e9occupation, n\u2019h\u00e9sitez pas \u00e0 <\/span><span style=\"color: #646b2d;\"><a style=\"color: #646b2d;\" href=\"https:\/\/dascostorage.com\/stging.ae\/index.php\/contact-us\/\">nous contacter.<\/a><\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e872b67 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e872b67\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-09d5afc\" data-id=\"09d5afc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bfef67b elementor-widget elementor-widget-heading\" data-id=\"bfef67b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Commandes, livraison et retours<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1889aa87 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1889aa87\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-15c23c51\" data-id=\"15c23c51\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-35fc5b81 elementor-widget elementor-widget-icon-box\" data-id=\"35fc5b81\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tCOMMANDER DES SOLUTIONS DE RANGEMENT ET D\u2019ENTREPOSAGE\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tLes commandes doivent \u00eatre accompagn\u00e9es d\u2019un bon de commande d\u00fbment  sign\u00e9, envoy\u00e9 par courriel ou en version papier \u00e0 DASCO Storage Solutions. D\u00e8s r\u00e9ception du bon de commande, une confirmation comprenant la description du produit, la couleur, le  prix et la date d\u2019exp\u00e9dition pr\u00e9vue sera transmise pour votre approbation et vos dossiers. \t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-458f3630 elementor-widget elementor-widget-icon-box\" data-id=\"458f3630\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tMODALIT\u00c9S DE PAIEMENT\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tLe paiement est effectu\u00e9 dans un d\u00e9lai net de 30 jours \u00e0 compter de la date de facturation.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3cbbaa46 elementor-widget elementor-widget-icon-box\" data-id=\"3cbbaa46\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tLivraison\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tDASCO Storage Solutions s\u2019engage \u00e0 produire et exp\u00e9dier les commandes dans  un d\u00e9lai de 20 \u00e0 25 jours ouvrables \u00e0 compter de leur r\u00e9ception. En raison de  facteurs hors de notre contr\u00f4le, tels que les p\u00e9riodes de pointe, les  commandes en gros volumes ou des demandes de personnalisations, le d\u00e9lai d'exp\u00e9dition peut  \u00eatre prolong\u00e9. Dans ce cas, les repr\u00e9sentants de DASCO vous informeront de tout  retard et\/ou changement.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-64ad6ee0 elementor-widget elementor-widget-icon-box\" data-id=\"64ad6ee0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tRetour de produits\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tTous les retours doivent faire l'objet d'une autorisation pr\u00e9alable de DASCO  Storage Solutions. Sans cette autorisation, aucun retour ne sera accept\u00e9. Un  num\u00e9ro d\u2019autorisation de retour (RMA) vous sera fourni et devra accompagner  l\u2019envoi. DASCO se r\u00e9serve le droit d\u2019imposer des frais de r\u00e9approvisionnement et\/ou de  transport pour les produits retourn\u00e9s qui ont \u00e9t\u00e9 fournis conform\u00e9ment au bon  de commande initial.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-59ef463b\" data-id=\"59ef463b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9c466fc elementor-widget elementor-widget-image\" data-id=\"9c466fc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/dascostorage.com\/wp-content\/uploads\/2022\/11\/constablepolice-scaled.jpg\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-20db61e2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"20db61e2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-df6449e\" data-id=\"df6449e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-16e23ab6 elementor-widget__width-auto elementor-absolute elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"16e23ab6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-94a7ccb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"94a7ccb\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a312995\" data-id=\"a312995\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e9633fa elementor-widget elementor-widget-menu-anchor\" data-id=\"e9633fa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"Soutien\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6d8076b elementor-widget elementor-widget-heading\" data-id=\"6d8076b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Besoin d\u2019aide? <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2492cfd elementor-widget elementor-widget-text-editor\" data-id=\"2492cfd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Si vous avez des questions sur nos produits ou nos composants, n&rsquo;h\u00e9sitez pas \u00e0 nous contacter.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bc55094 elementor-button-align-stretch elementor-widget elementor-widget-global elementor-global-7735 elementor-global-5423 elementor-widget-form\" data-id=\"bc55094\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"contact-form\" data-settings=\"{&quot;button_width&quot;:&quot;30&quot;,&quot;step_next_label&quot;:&quot;Suivant&quot;,&quot;step_previous_label&quot;:&quot;Pr\\u00e9c\\u00e9dent&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" name=\"Formulaire de contact\" aria-label=\"Formulaire de contact\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"7659\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"bc55094\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"Dasco Storage Solutions\" \/>\n\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-above\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-name elementor-col-50 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-name\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tNom\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[name]\" id=\"form-field-name\" class=\"elementor-field elementor-size-md  elementor-field-textual\" placeholder=\"Nom\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-tel elementor-field-group elementor-column elementor-field-group-field_4cb3b73 elementor-col-50\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_4cb3b73\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tNum\u00e9ro de t\u00e9l\u00e9phone\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t<input size=\"1\" type=\"tel\" name=\"form_fields[field_4cb3b73]\" id=\"form-field-field_4cb3b73\" class=\"elementor-field elementor-size-md  elementor-field-textual\" placeholder=\"xxx-xxx-xxxx\" pattern=\"[0-9()#&amp;+*-=.]+\" title=\"Seuls les caract\u00e8res de num\u00e9ros de t\u00e9l\u00e9phone (#, -, *, etc.) sont accept\u00e9s.\">\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-email elementor-col-50 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-email\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tE-mail\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-md  elementor-field-textual\" placeholder=\"E-mail\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-field_5d710c1 elementor-col-50 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_5d710c1\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tCode postal\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[field_5d710c1]\" id=\"form-field-field_5d710c1\" class=\"elementor-field elementor-size-md  elementor-field-textual\" placeholder=\"Code postal\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-field_98c7a1d elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_98c7a1d\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tSujet\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[field_98c7a1d]\" id=\"form-field-field_98c7a1d\" class=\"elementor-field elementor-size-md  elementor-field-textual\" placeholder=\"Sujet\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-textarea elementor-field-group elementor-column elementor-field-group-message elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-message\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tMessage\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<textarea class=\"elementor-field-textual elementor-field  elementor-size-md\" name=\"form_fields[message]\" id=\"form-field-message\" rows=\"4\" placeholder=\"Message\" required=\"required\"><\/textarea>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-recaptcha_v3 elementor-field-group elementor-column elementor-field-group-field_7985d0b elementor-col-100 recaptcha_v3-inline\">\n\t\t\t\t\t<div class=\"elementor-field\" id=\"form-field-field_7985d0b\"><div class=\"elementor-g-recaptcha\" data-sitekey=\"6LfaTawlAAAAAGeO7lLVUze9MecjOJKNsiBe3vlj\" data-type=\"v3\" data-action=\"Form\" data-badge=\"inline\" data-size=\"invisible\"><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-30 e-form__buttons\">\n\t\t\t\t\t<button class=\"elementor-button elementor-size-sm\" type=\"submit\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Envoyer<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/form>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>A&nbsp;propos&nbsp;de&nbsp;nous Notre histoire Chez DASCO Storage Solutions, nous sommes fiers de fournir les meilleurs produits, ainsi qu\u2019un service \u00e0 la client\u00e8le hors pair.\u00a0 Nous sommes les\u00a0 leaders de l\u2019industrie, sp\u00e9cialis\u00e9s dans les solutions de stockage s\u00e9curis\u00e9es pour les armes, les pi\u00e8ces \u00e0 conviction, les appareils \u00e9lectroniques et les dossiers confidentiels pour les forces arm\u00e9es, les [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-7659","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00c0 propos de nous - Dasco Storage Solutions<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dascostorage.com\/fr\/a-propos-de-nous\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00c0 propos de nous - Dasco Storage Solutions\" \/>\n<meta property=\"og:description\" content=\"A&nbsp;propos&nbsp;de&nbsp;nous Notre histoire Chez DASCO Storage Solutions, nous sommes fiers de fournir les meilleurs produits, ainsi qu\u2019un service \u00e0 la client\u00e8le hors pair.\u00a0 Nous sommes les\u00a0 leaders de l\u2019industrie, sp\u00e9cialis\u00e9s dans les solutions de stockage s\u00e9curis\u00e9es pour les armes, les pi\u00e8ces \u00e0 conviction, les appareils \u00e9lectroniques et les dossiers confidentiels pour les forces arm\u00e9es, les [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dascostorage.com\/fr\/a-propos-de-nous\/\" \/>\n<meta property=\"og:site_name\" content=\"Dasco Storage Solutions\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=100028941325482\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-09T16:43:43+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dascostorage.com\\\/fr\\\/a-propos-de-nous\\\/\",\"url\":\"https:\\\/\\\/dascostorage.com\\\/fr\\\/a-propos-de-nous\\\/\",\"name\":\"\u00c0 propos de nous - Dasco Storage Solutions\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dascostorage.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dascostorage.com\\\/fr\\\/a-propos-de-nous\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dascostorage.com\\\/fr\\\/a-propos-de-nous\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dascostorage.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/constablepolice-1024x1024.jpg\",\"datePublished\":\"2022-10-05T15:22:08+00:00\",\"dateModified\":\"2025-07-09T16:43:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dascostorage.com\\\/fr\\\/a-propos-de-nous\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dascostorage.com\\\/fr\\\/a-propos-de-nous\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dascostorage.com\\\/fr\\\/a-propos-de-nous\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dascostorage.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/constablepolice-1024x1024.jpg\",\"contentUrl\":\"https:\\\/\\\/dascostorage.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/constablepolice-1024x1024.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dascostorage.com\\\/fr\\\/a-propos-de-nous\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dascostorage.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c0 propos de nous\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dascostorage.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/dascostorage.com\\\/fr\\\/\",\"name\":\"Dasco Storage Solutions\",\"description\":\"High-security storage solutions for law enforcement, militaries, government facilities, public institutions, and more.\",\"publisher\":{\"@id\":\"https:\\\/\\\/dascostorage.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dascostorage.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dascostorage.com\\\/fr\\\/#organization\",\"name\":\"Dasco Storage Solutions\",\"url\":\"https:\\\/\\\/dascostorage.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dascostorage.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dascostorage.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Dasco-Logo-1.png\",\"contentUrl\":\"https:\\\/\\\/dascostorage.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Dasco-Logo-1.png\",\"width\":1941,\"height\":556,\"caption\":\"Dasco Storage Solutions\"},\"image\":{\"@id\":\"https:\\\/\\\/dascostorage.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=100028941325482\",\"https:\\\/\\\/www.instagram.com\\\/dascostoragesolutions\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00c0 propos de nous - Dasco Storage Solutions","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dascostorage.com\/fr\/a-propos-de-nous\/","og_locale":"fr_FR","og_type":"article","og_title":"\u00c0 propos de nous - Dasco Storage Solutions","og_description":"A&nbsp;propos&nbsp;de&nbsp;nous Notre histoire Chez DASCO Storage Solutions, nous sommes fiers de fournir les meilleurs produits, ainsi qu\u2019un service \u00e0 la client\u00e8le hors pair.\u00a0 Nous sommes les\u00a0 leaders de l\u2019industrie, sp\u00e9cialis\u00e9s dans les solutions de stockage s\u00e9curis\u00e9es pour les armes, les pi\u00e8ces \u00e0 conviction, les appareils \u00e9lectroniques et les dossiers confidentiels pour les forces arm\u00e9es, les [&hellip;]","og_url":"https:\/\/dascostorage.com\/fr\/a-propos-de-nous\/","og_site_name":"Dasco Storage Solutions","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=100028941325482","article_modified_time":"2025-07-09T16:43:43+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dascostorage.com\/fr\/a-propos-de-nous\/","url":"https:\/\/dascostorage.com\/fr\/a-propos-de-nous\/","name":"\u00c0 propos de nous - Dasco Storage Solutions","isPartOf":{"@id":"https:\/\/dascostorage.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dascostorage.com\/fr\/a-propos-de-nous\/#primaryimage"},"image":{"@id":"https:\/\/dascostorage.com\/fr\/a-propos-de-nous\/#primaryimage"},"thumbnailUrl":"https:\/\/dascostorage.com\/wp-content\/uploads\/2022\/11\/constablepolice-1024x1024.jpg","datePublished":"2022-10-05T15:22:08+00:00","dateModified":"2025-07-09T16:43:43+00:00","breadcrumb":{"@id":"https:\/\/dascostorage.com\/fr\/a-propos-de-nous\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dascostorage.com\/fr\/a-propos-de-nous\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dascostorage.com\/fr\/a-propos-de-nous\/#primaryimage","url":"https:\/\/dascostorage.com\/wp-content\/uploads\/2022\/11\/constablepolice-1024x1024.jpg","contentUrl":"https:\/\/dascostorage.com\/wp-content\/uploads\/2022\/11\/constablepolice-1024x1024.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/dascostorage.com\/fr\/a-propos-de-nous\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dascostorage.com\/fr\/"},{"@type":"ListItem","position":2,"name":"\u00c0 propos de nous"}]},{"@type":"WebSite","@id":"https:\/\/dascostorage.com\/fr\/#website","url":"https:\/\/dascostorage.com\/fr\/","name":"Dasco Storage Solutions","description":"High-security storage solutions for law enforcement, militaries, government facilities, public institutions, and more.","publisher":{"@id":"https:\/\/dascostorage.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dascostorage.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/dascostorage.com\/fr\/#organization","name":"Dasco Storage Solutions","url":"https:\/\/dascostorage.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dascostorage.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/dascostorage.com\/wp-content\/uploads\/2022\/09\/Dasco-Logo-1.png","contentUrl":"https:\/\/dascostorage.com\/wp-content\/uploads\/2022\/09\/Dasco-Logo-1.png","width":1941,"height":556,"caption":"Dasco Storage Solutions"},"image":{"@id":"https:\/\/dascostorage.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100028941325482","https:\/\/www.instagram.com\/dascostoragesolutions\/"]}]}},"_links":{"self":[{"href":"https:\/\/dascostorage.com\/fr\/wp-json\/wp\/v2\/pages\/7659","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dascostorage.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dascostorage.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dascostorage.com\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/dascostorage.com\/fr\/wp-json\/wp\/v2\/comments?post=7659"}],"version-history":[{"count":20,"href":"https:\/\/dascostorage.com\/fr\/wp-json\/wp\/v2\/pages\/7659\/revisions"}],"predecessor-version":[{"id":8090,"href":"https:\/\/dascostorage.com\/fr\/wp-json\/wp\/v2\/pages\/7659\/revisions\/8090"}],"wp:attachment":[{"href":"https:\/\/dascostorage.com\/fr\/wp-json\/wp\/v2\/media?parent=7659"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}